{"id":104376,"date":"2024-06-04T09:12:15","date_gmt":"2024-06-04T07:12:15","guid":{"rendered":"https:\/\/www.piemontehouses.com\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/"},"modified":"2024-07-24T16:18:18","modified_gmt":"2024-07-24T14:18:18","slug":"bossolasco-panoramabauernhaus-mit-land-zu-verkaufen","status":"publish","type":"immobile","link":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/","title":{"rendered":"Bossolasco Panoramabauernhaus mit Land zu verkaufen"},"content":{"rendered":"<p>Nicht weit von dem charakteristischen Dorf Bossolasco, der Perle der Langhe, liegt dieses alte Geh\u00f6ft, das aus 2 Geb\u00e4uden besteht, die senkrecht zueinander angeordnet sind und die klassische L-Form bilden. Ein Geb\u00e4ude diente als Wohnhaus, das zweite als Stall und Scheune.<br \/>  Bei der Renovierung wurden die beiden Geb\u00e4ude durch einen Portikus verbunden, der heute als Garage dient und \u00fcber dem sich eine Terrasse befindet.<br \/>  Das erste Geb\u00e4ude verf\u00fcgt \u00fcber Kellerr\u00e4ume und eine Heizungsanlage im Untergeschoss, eine K\u00fcche und ein Wohnzimmer im ersten Stock und zwei Schlafzimmer, eines davon mit einem Ankleidezimmer, im zweiten Stock.<br \/>  Der ehemalige Stall mit Heuboden verf\u00fcgt heute \u00fcber einen gro\u00dfen Raum im Erdgeschoss, der als Bibliothek genutzt wird, eine kleine Sommerk\u00fcche mit Zugang zu einem \u00fcberdachten Au\u00dfenbereich und einen Servicebereich.<br \/>  Im ersten Stock, der ehemaligen Scheune, befinden sich ein gro\u00dfes Wohnzimmer, das durch gro\u00dfe Bogenfenster erhellt wird, ein Badezimmer und ein Abstellraum.<br \/>  Im zweiten Stock gibt es ein Zwischengeschoss, das \u00fcber eine Wendeltreppe erreichbar ist und ein weiteres Wohnzimmer und ein Schlafzimmer umfasst, beides Zimmer im Dachgeschoss.<br \/>  Die Geb\u00e4ude sind in einem bewohnbaren Zustand. Es k\u00f6nnen Verbesserungsvorschl\u00e4ge gemacht werden, um den Komfort und die Energieeffizienz zu erh\u00f6hen, vielleicht unter Ausnutzung der j\u00fcngsten staatlichen Anreize.<br \/>Es wurde eine 5 kW\/h-Photovoltaikanlage installiert, die \u00fcber ein Strahlungspaneel auch zur Beheizung eines Raumes dient.<br \/>  Das Grundst\u00fcck, das teilweise eingez\u00e4unt ist, erstreckt sich \u00fcber 2 Hektar rund um die Geb\u00e4ude und ist mit Haseln\u00fcssen bepflanzt, einer typischen Kulturpflanze der Region.<br \/>  Die Lage ist besonders hell, ruhig und panoramisch, da sie nach Westen ausgerichtet ist und somit einen gro\u00dfen Teil des westlichen Alpenbogens \u00fcberblickt.<br \/>  Ein bequemer Spaziergang f\u00fchrt Sie nach Bossolasco, wo Sie ausgezeichnete Restaurants und Gesch\u00e4fte mit lokalen Produkten finden. Alba ist weniger als 30 km entfernt, und Sie k\u00f6nnen angenehme Tagesausfl\u00fcge zu den T\u00e4lern und Skipisten der Seealpen oder zu den Str\u00e4nden der ligurischen Riviera unternehmen.<\/p>\n","protected":false},"featured_media":34724,"template":"","meta":{"_acf_changed":false,"footnotes":""},"circuito":[],"tipologia":[94,85],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses\" \/>\n<meta property=\"og:description\" content=\"Nicht weit von dem charakteristischen Dorf Bossolasco, der Perle der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/\" \/>\n<meta property=\"og:site_name\" content=\"Piemonte Houses\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T14:18:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/\",\"name\":\"Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses\",\"isPartOf\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg\",\"datePublished\":\"2024-06-04T07:12:15+00:00\",\"dateModified\":\"2024-07-24T14:18:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage\",\"url\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg\",\"contentUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.piemontehouses.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bossolasco Panoramabauernhaus mit Land zu verkaufen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/\",\"name\":\"Piemonte Houses\",\"description\":\"Real estate agency - Langhe - Monferrato - Roero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/","og_locale":"de_DE","og_type":"article","og_title":"Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses","og_description":"Nicht weit von dem charakteristischen Dorf Bossolasco, der Perle der [&hellip;]","og_url":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/","og_site_name":"Piemonte Houses","article_modified_time":"2024-07-24T14:18:18+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/","url":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/","name":"Bossolasco Panoramabauernhaus mit Land zu verkaufen - Piemonte Houses","isPartOf":{"@id":"https:\/\/www.piemontehouses.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage"},"image":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg","datePublished":"2024-06-04T07:12:15+00:00","dateModified":"2024-07-24T14:18:18+00:00","breadcrumb":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#primaryimage","url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg","contentUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/430_bossolasco_cascina_vendita_101-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/bossolasco-panoramabauernhaus-mit-land-zu-verkaufen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.piemontehouses.com\/de\/"},{"@type":"ListItem","position":2,"name":"Bossolasco Panoramabauernhaus mit Land zu verkaufen"}]},{"@type":"WebSite","@id":"https:\/\/www.piemontehouses.com\/de\/#website","url":"https:\/\/www.piemontehouses.com\/de\/","name":"Piemonte Houses","description":"Real estate agency - Langhe - Monferrato - Roero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104376"}],"collection":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile"}],"about":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/types\/immobile"}],"version-history":[{"count":1,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104376\/revisions"}],"predecessor-version":[{"id":106106,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104376\/revisions\/106106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media\/34724"}],"wp:attachment":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media?parent=104376"}],"wp:term":[{"taxonomy":"circuito","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/circuito?post=104376"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/tipologia?post=104376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}