{"id":104807,"date":"2024-06-04T10:58:22","date_gmt":"2024-06-04T08:58:22","guid":{"rendered":"https:\/\/www.piemontehouses.com\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/"},"modified":"2024-07-24T16:21:09","modified_gmt":"2024-07-24T14:21:09","slug":"weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato","status":"publish","type":"immobile","link":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/","title":{"rendered":"Weingut mit etablierten Marken in Italien und im Ausland &#8211; Monferrato"},"content":{"rendered":"<p>ITALIEN PIEDMONT MONFERRATO (ASTI) Weingut mit etablierten Marken in Italien und im Ausland.<br \/>Das Unternehmen hat:  <br \/>7 ha DOCG-Weinberge, alle in Produktion (Alter von 1997 bis 2013)<\/p>\n<p>-Schuppen von ca. 1000 m2 (Weinkeller, B\u00fcro, Verkostungsraum, Labor) -Lagergeb\u00e4ude von ca. 400 m2 f\u00fcr die Lagerung von landwirtschaftlichen Ger\u00e4ten und Lager -Weinkellerausr\u00fcstung, einschlie\u00dflich o Weinherstellungslinie mit Brecher-Stampfer, Elevator, Presse o Edelstahltanks, Glasf\u00e4sser, F\u00e4sser, Pumpen und Kellerleitungen<br \/>o Abf\u00fcllanlage 2500 Flaschen\/h<\/p>\n<p>&#8211; Landwirtschaftliche Ger\u00e4te o Traktor f\u00fcr Weinberge o Traktor mit gro\u00dfen R\u00e4dern o Raupenschlepper o Komplette Ausr\u00fcstung f\u00fcr die mechanisierte Bewirtschaftung von Weinbergen.<br \/>&#8211; 20KW-Photovoltaikanlage<\/p>\n<p>PRODUKTE UND M\u00c4RKTE Das Unternehmen hat die wichtigsten piemontesischen Weine in seinem Katalog: edle Rotweine (Barolo, Barbaresco), typische piemontesische Rotweine (Barbera, Nebbiolo, Grignolino, Ruch\u00e9), Gavi, Moscato und Schaumweine nach klassischer Methode. Das Unternehmen verkauft etwa 75.000 Flaschen\/Jahr, obwohl es f\u00fcr eine viel h\u00f6here Produktion ausger\u00fcstet ist.<\/p>\n<p>Die verkauften Weine stammen aus den eigenen Trauben, aus Trauben, die auf dem Weingut gekauft und vinifiziert werden, und von treuen Lieferanten f\u00fcr die Produktion, die aufgrund des Produktionsprozesses oder der Spezifikationen nicht auf dem Weingut hergestellt werden k\u00f6nnen. Der Verkauf verteilt sich auf Italien 24% Ausland 76%<\/p>\n<p>SCHL\u00dcSSELMERKMALE DES UNTERNEHMENS &#8211; Ausgezeichnetes Qualit\u00e4tsniveau der Produkte <\/p>\n<p> Ausgezeichnete Bewertungen in nationalen F\u00fchrern und internationalen Magazinen &#8211; Weit verzweigtes Vertriebsnetz &#8211; Konsolidierte Partnerschaft mit Qualit\u00e4tslieferanten von Trauben und Weinen &#8211; An das Kellereizentrum angrenzende Weinberge mit guter Lage &#8211; Panoramalage des Kellereizentrums &#8211; M\u00f6glichkeit der Erweiterung der Rebfl\u00e4che &#8211; M\u00f6glichkeit der Erweiterung der bestehenden Kellereieinrichtungen &#8211; Gen\u00fcgend Platz f\u00fcr neue Geb\u00e4ude<\/p>\n","protected":false},"featured_media":117427,"template":"","meta":{"_acf_changed":false,"footnotes":""},"circuito":[78],"tipologia":[108,90],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses\" \/>\n<meta property=\"og:description\" content=\"ITALIEN PIEDMONT MONFERRATO (ASTI) Weingut mit etablierten Marken in Italien [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/\" \/>\n<meta property=\"og:site_name\" content=\"Piemonte Houses\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T14:21:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/\",\"name\":\"Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses\",\"isPartOf\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp\",\"datePublished\":\"2024-06-04T08:58:22+00:00\",\"dateModified\":\"2024-07-24T14:21:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage\",\"url\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp\",\"contentUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp\",\"width\":1408,\"height\":792},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.piemontehouses.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weingut mit etablierten Marken in Italien und im Ausland &#8211; Monferrato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/\",\"name\":\"Piemonte Houses\",\"description\":\"Real estate agency - Langhe - Monferrato - Roero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/","og_locale":"de_DE","og_type":"article","og_title":"Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses","og_description":"ITALIEN PIEDMONT MONFERRATO (ASTI) Weingut mit etablierten Marken in Italien [&hellip;]","og_url":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/","og_site_name":"Piemonte Houses","article_modified_time":"2024-07-24T14:21:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/","url":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/","name":"Weingut mit etablierten Marken in Italien und im Ausland - Monferrato - Piemonte Houses","isPartOf":{"@id":"https:\/\/www.piemontehouses.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage"},"image":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp","datePublished":"2024-06-04T08:58:22+00:00","dateModified":"2024-07-24T14:21:09+00:00","breadcrumb":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#primaryimage","url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp","contentUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/monf.webp","width":1408,"height":792},{"@type":"BreadcrumbList","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/weingut-mit-etablierten-marken-in-italien-und-im-ausland-monferrato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.piemontehouses.com\/de\/"},{"@type":"ListItem","position":2,"name":"Weingut mit etablierten Marken in Italien und im Ausland &#8211; Monferrato"}]},{"@type":"WebSite","@id":"https:\/\/www.piemontehouses.com\/de\/#website","url":"https:\/\/www.piemontehouses.com\/de\/","name":"Piemonte Houses","description":"Real estate agency - Langhe - Monferrato - Roero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104807"}],"collection":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile"}],"about":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/types\/immobile"}],"version-history":[{"count":1,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104807\/revisions"}],"predecessor-version":[{"id":106336,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104807\/revisions\/106336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media\/117427"}],"wp:attachment":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media?parent=104807"}],"wp:term":[{"taxonomy":"circuito","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/circuito?post=104807"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/tipologia?post=104807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}