{"id":104899,"date":"2024-06-04T10:38:01","date_gmt":"2024-06-04T08:38:01","guid":{"rendered":"https:\/\/www.piemontehouses.com\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/"},"modified":"2024-07-24T16:21:59","modified_gmt":"2024-07-24T14:21:59","slug":"steinhaeuser-zur-renovierung-mit-grundstueck","status":"publish","type":"immobile","link":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/","title":{"rendered":"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck"},"content":{"rendered":"<p>In den Langhe, in einer h\u00fcgeligen und panoramischen Lage, Gruppe von 3 rustikalen H\u00e4usern aus authentischem Langa-Stein, mit Innenhof und Land.<br \/>  Das erste Rustico ist ein Haus mit einer Eingangshalle, einer K\u00fcche, einem Wohnzimmer und einem Badezimmer im Erdgeschoss. Im ersten Stock, erreichbar \u00fcber eine Au\u00dfentreppe, 3 Schlafzimmer, die vom Balkon aus zug\u00e4nglich sind.<br \/>  Das zweite Haus hat f\u00fcnf Zimmer im Erdgeschoss und weitere f\u00fcnf im ersten Stock.<br \/>  Das dritte Rustico ist ein ehemaliger Stall mit einer zweischiffigen Scheune.<br \/>  Das Land ist in zwei freistehende K\u00f6rper aufgeteilt: einer in einem mit den Geb\u00e4uden (etwa 3000 Quadratmeter), der Rest (\u00fcber 9000 Quadratmeter) ein paar Meter entfernt, mit Haseln\u00fcssen bebaut.<br \/>  Es gibt noch zwei weitere bewohnte H\u00e4user in dem Weiler, die sich hinter dem hier vorgeschlagenen Grundst\u00fcck befinden.<br \/>  Eine angemessene Renovierung, die den authentischen, traditionellen Charakter des Hauses respektiert, k\u00f6nnte zu einem faszinierenden Objekt f\u00fchren, das sich in einer sehr angenehmen, ruhigen Lage befindet, aber gleichzeitig nicht weit von bewohnten Zentren mit den wichtigsten Dienstleistungen entfernt ist.<br \/>  Das Grundst\u00fcck kann auch f\u00fcr den Tourismus genutzt werden.<br \/>  Ausgezeichnetes Preis-Leistungs-Verh\u00e4ltnis.<\/p>\n","protected":false},"featured_media":66197,"template":"","meta":{"_acf_changed":false,"footnotes":""},"circuito":[],"tipologia":[94,85],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses\" \/>\n<meta property=\"og:description\" content=\"In den Langhe, in einer h\u00fcgeligen und panoramischen Lage, Gruppe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/\" \/>\n<meta property=\"og:site_name\" content=\"Piemonte Houses\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T14:21:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_1_3_rustici_in_pietra_76-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/\",\"name\":\"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses\",\"isPartOf\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg\",\"datePublished\":\"2024-06-04T08:38:01+00:00\",\"dateModified\":\"2024-07-24T14:21:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage\",\"url\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg\",\"contentUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.piemontehouses.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.piemontehouses.com\/de\/#website\",\"url\":\"https:\/\/www.piemontehouses.com\/de\/\",\"name\":\"Piemonte Houses\",\"description\":\"Real estate agency - Langhe - Monferrato - Roero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/","og_locale":"de_DE","og_type":"article","og_title":"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses","og_description":"In den Langhe, in einer h\u00fcgeligen und panoramischen Lage, Gruppe [&hellip;]","og_url":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/","og_site_name":"Piemonte Houses","article_modified_time":"2024-07-24T14:21:59+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_1_3_rustici_in_pietra_76-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/","url":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/","name":"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck - Piemonte Houses","isPartOf":{"@id":"https:\/\/www.piemontehouses.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage"},"image":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage"},"thumbnailUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg","datePublished":"2024-06-04T08:38:01+00:00","dateModified":"2024-07-24T14:21:59+00:00","breadcrumb":{"@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#primaryimage","url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg","contentUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/490_3_rustici_in_pietra_53-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.piemontehouses.com\/de\/immobile\/steinhaeuser-zur-renovierung-mit-grundstueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.piemontehouses.com\/de\/"},{"@type":"ListItem","position":2,"name":"Steinh\u00e4user zur Renovierung mit Grundst\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/www.piemontehouses.com\/de\/#website","url":"https:\/\/www.piemontehouses.com\/de\/","name":"Piemonte Houses","description":"Real estate agency - Langhe - Monferrato - Roero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.piemontehouses.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104899"}],"collection":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile"}],"about":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/types\/immobile"}],"version-history":[{"count":1,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104899\/revisions"}],"predecessor-version":[{"id":106440,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/immobile\/104899\/revisions\/106440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media\/66197"}],"wp:attachment":[{"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/media?parent=104899"}],"wp:term":[{"taxonomy":"circuito","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/circuito?post=104899"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/de\/wp-json\/wp\/v2\/tipologia?post=104899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}