{"id":104900,"date":"2024-06-04T10:38:01","date_gmt":"2024-06-04T08:38:01","guid":{"rendered":"https:\/\/www.piemontehouses.com\/immobile\/landbouwgrond-10-ha-met-ruine\/"},"modified":"2024-07-24T16:21:58","modified_gmt":"2024-07-24T14:21:58","slug":"landbouwgrond-10-ha-met-ruine","status":"publish","type":"immobile","link":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/","title":{"rendered":"Landbouwgrond 10 ha met ru\u00efne"},"content":{"rendered":"<p>In Alta Langa op ongeveer 600 m boven zeeniveau ligt landbouwgrond van ongeveer 10 ha in \u00e9\u00e9n enkele massa, bebouwbaar, met grote ru\u00efnes erin. De grond is bijna volledig grasland, weiland en bouwland, dus geschikt voor elk type teelt.<\/p>\n<div>Zeer geschikt voor het aanplanten van wijngaarden voor Alta Langa, voldoet volledig aan de eisen van het bestek. <\/p>\n<p>Het is ook mogelijk om een hazelnootteelt te realiseren. Het gebied is ongerept en leent zich voor biologische of biodynamische teelt. Het gebouw is in principe een ru\u00efne, maar biedt een overvloedige bruikbare oppervlakte (meer dan 800 m\u00b2) en is gelegen op een panoramische en zeer rustige locatie, waardoor het pand interessant is voor degenen die een productielocatie en\/of een toeristisch resort willen opzetten. De toegang moet worden gerealiseerd, evenals de aansluitingen op de waterleiding. Uniek object gezien de samenhang in \u00e9\u00e9n geheel.<\/p><\/div>\n","protected":false},"featured_media":66301,"template":"","meta":{"_acf_changed":false,"footnotes":""},"circuito":[76],"tipologia":[109,86],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses\" \/>\n<meta property=\"og:description\" content=\"In Alta Langa op ongeveer 600 m boven zeeniveau ligt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/\" \/>\n<meta property=\"og:site_name\" content=\"Piemonte Houses\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T14:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_sat-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/\",\"url\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/\",\"name\":\"Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses\",\"isPartOf\":{\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg\",\"datePublished\":\"2024-06-04T08:38:01+00:00\",\"dateModified\":\"2024-07-24T14:21:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage\",\"url\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg\",\"contentUrl\":\"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.piemontehouses.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landbouwgrond 10 ha met ru\u00efne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.piemontehouses.com\/nl\/#website\",\"url\":\"https:\/\/www.piemontehouses.com\/nl\/\",\"name\":\"Piemonte Houses\",\"description\":\"Real estate agency - Langhe - Monferrato - Roero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.piemontehouses.com\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/","og_locale":"nl_NL","og_type":"article","og_title":"Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses","og_description":"In Alta Langa op ongeveer 600 m boven zeeniveau ligt [&hellip;]","og_url":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/","og_site_name":"Piemonte Houses","article_modified_time":"2024-07-24T14:21:58+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_sat-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/","url":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/","name":"Landbouwgrond 10 ha met ru\u00efne - Piemonte Houses","isPartOf":{"@id":"https:\/\/www.piemontehouses.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage"},"image":{"@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg","datePublished":"2024-06-04T08:38:01+00:00","dateModified":"2024-07-24T14:21:58+00:00","breadcrumb":{"@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#primaryimage","url":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg","contentUrl":"https:\/\/www.piemontehouses.com\/wp-content\/uploads\/2024\/06\/569_p1030360.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.piemontehouses.com\/nl\/immobile\/landbouwgrond-10-ha-met-ruine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.piemontehouses.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Landbouwgrond 10 ha met ru\u00efne"}]},{"@type":"WebSite","@id":"https:\/\/www.piemontehouses.com\/nl\/#website","url":"https:\/\/www.piemontehouses.com\/nl\/","name":"Piemonte Houses","description":"Real estate agency - Langhe - Monferrato - Roero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.piemontehouses.com\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/immobile\/104900"}],"collection":[{"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/immobile"}],"about":[{"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/types\/immobile"}],"version-history":[{"count":1,"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/immobile\/104900\/revisions"}],"predecessor-version":[{"id":106439,"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/immobile\/104900\/revisions\/106439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/media\/66301"}],"wp:attachment":[{"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/media?parent=104900"}],"wp:term":[{"taxonomy":"circuito","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/circuito?post=104900"},{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.piemontehouses.com\/nl\/wp-json\/wp\/v2\/tipologia?post=104900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}